{"id":1352,"date":"2023-05-04T17:07:23","date_gmt":"2023-05-04T17:07:23","guid":{"rendered":"https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008.jpg"},"modified":"2023-05-04T17:07:23","modified_gmt":"2023-05-04T17:07:23","slug":"img-20230501-wa0008","status":"inherit","type":"attachment","link":"https:\/\/www.adoptarivertt.com\/website\/img-20230501-wa0008\/","title":{"rendered":"IMG-20230501-WA0008"},"author":5,"comment_status":"","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008.jpg'><img width=\"300\" height=\"150\" src=\"https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008-300x150.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008-300x150.jpg 300w, https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008-768x385.jpg 768w, https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008.jpg 840w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":840,"height":421,"file":"2023\/05\/IMG-20230501-WA0008.jpg","filesize":213655,"sizes":{"medium":{"file":"IMG-20230501-WA0008-300x150.jpg","width":300,"height":150,"filesize":21562,"mime_type":"image\/jpeg","source_url":"https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008-300x150.jpg"},"thumbnail":{"file":"IMG-20230501-WA0008-150x150.jpg","width":150,"height":150,"filesize":11236,"mime_type":"image\/jpeg","source_url":"https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008-150x150.jpg"},"medium_large":{"file":"IMG-20230501-WA0008-768x385.jpg","width":768,"height":385,"filesize":96755,"mime_type":"image\/jpeg","source_url":"https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008-768x385.jpg"},"tilak-featured-image":{"file":"IMG-20230501-WA0008-540x284.jpg","width":540,"height":284,"filesize":58229,"mime_type":"image\/jpeg","source_url":"https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008-540x284.jpg"},"tilak-single-featured-image":{"file":"IMG-20230501-WA0008-770x420.jpg","width":770,"height":420,"filesize":102881,"mime_type":"image\/jpeg","source_url":"https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008-770x420.jpg"},"tilak-event-list":{"file":"IMG-20230501-WA0008-540x300.jpg","width":540,"height":300,"filesize":60182,"mime_type":"image\/jpeg","source_url":"https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008-540x300.jpg"},"tilak-donation-featured-image":{"file":"IMG-20230501-WA0008-540x365.jpg","width":540,"height":365,"filesize":67280,"mime_type":"image\/jpeg","source_url":"https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008-540x365.jpg"},"tilak-sermons-list":{"file":"IMG-20230501-WA0008-220x260.jpg","width":220,"height":260,"filesize":23357,"mime_type":"image\/jpeg","source_url":"https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008-220x260.jpg"},"tilak-blog-post":{"file":"IMG-20230501-WA0008-570x300.jpg","width":570,"height":300,"filesize":63636,"mime_type":"image\/jpeg","source_url":"https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008-570x300.jpg"},"full":{"file":"IMG-20230501-WA0008.jpg","width":840,"height":421,"mime_type":"image\/jpeg","source_url":"https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.adoptarivertt.com\/website\/wp-content\/uploads\/2023\/05\/IMG-20230501-WA0008.jpg","_links":{"self":[{"href":"https:\/\/www.adoptarivertt.com\/website\/wp-json\/wp\/v2\/media\/1352"}],"collection":[{"href":"https:\/\/www.adoptarivertt.com\/website\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.adoptarivertt.com\/website\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.adoptarivertt.com\/website\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adoptarivertt.com\/website\/wp-json\/wp\/v2\/comments?post=1352"}]}}